

{"id":1186,"date":"2020-11-05T15:07:34","date_gmt":"2020-11-05T14:07:34","guid":{"rendered":"http:\/\/residenciarucab.es\/blog\/?p=1186"},"modified":"2020-11-06T09:27:09","modified_gmt":"2020-11-06T08:27:09","slug":"libros-para-el-confinamiento","status":"publish","type":"post","link":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/","title":{"rendered":"Libros para el confinamiento en la RUCAB"},"content":{"rendered":"<h4>\u00bfAburrimiento durante el aislamiento? queremos cambiarlo y hacerlo m\u00e1s ameno, os traemos &#8216;libros para el confinamiento&#8217;, ser\u00e1 de gran ayuda poner a disposici\u00f3n de los residentes confinados por el covid-19 el acceso a libros de tipo literario. En este post te explicamos c\u00f3mo tienes que hacerlo.<\/h4>\n<p>Ahora muchas personas est\u00e1n <strong>confinadas<\/strong>, y en la <strong>RUCAB<\/strong> no \u00edbamos a ser menos; todos estamos deseando viajar o salir de la habitaci\u00f3n, si cre\u00edas que no pod\u00edas hacerlo est\u00e1s equivocado. Presta atenci\u00f3n, y <strong>sigue leyendo<\/strong>.<\/p>\n<p>Contamos con <strong>m\u00e1s de 50 libros<\/strong>\u00a0 de todo tipo; leer te permite viajar a cualquier lugar del mundo y a cualquier \u00e9poca. Si ahora no pasas por el momento m\u00e1s divertido y las paredes de tu habitaci\u00f3n se te vienen encima, leer es la mejor opci\u00f3n. Esta es la lista de libros que tenemos actualmente:<\/p>\n<ol>\n<li><strong>El laberinto de la Atl\u00e1ntida<\/strong> (\u00c1lvaro Bermejo)<\/li>\n<li><strong>R\u00e9cords que nunca aparecer\u00e1n en el Guiness<\/strong> (Jos\u00e9 Montes)<\/li>\n<li><strong>El cielo en un infierno cabe<\/strong> (Cristina L\u00f3pez Barrio)<\/li>\n<li><strong>Las sandalias del Pescador<\/strong> (Morris West)<\/li>\n<li><strong>Anatema<\/strong> (Neal Stephenson)<\/li>\n<li><strong>Milena o el f\u00e9mur m\u00e1s bello del mundo<\/strong> (Jorge Zepeda Patterson)<\/li>\n<li><strong>La gaya ciencia<\/strong> (Friedrich Nietzsche)<\/li>\n<li><strong>La cosecha de Samhein<\/strong> (Jos\u00e9 Antonio Cotria)<\/li>\n<li><strong>La bestia<\/strong> (Peter Benchley)<\/li>\n<li><strong>El perfume<\/strong> (Patrick S\u00fcskind).<\/li>\n<li><strong>La leyenda de los piratas<\/strong> (Mar\u00eda Vila)<\/li>\n<li><strong>Groucho, una biograf\u00eda<\/strong> (Stefan Kanfer)<\/li>\n<li><strong>La crisis ninja y otros misterios<\/strong> (Leopoldo Abad\u00eda)<\/li>\n<li><strong>La hora de los sensatos<\/strong> (Leopoldo Abad\u00eda)<\/li>\n<li><strong>No somos nadie 2<\/strong> (Pablo Motos)<\/li>\n<li><strong>El horror de Dunwich<\/strong> (H. P. Lovecraft)<\/li>\n<li><strong>La hora del vampiro<\/strong> (Stephen King)<\/li>\n<li><strong>Vlad, la novela que retrata el verdadero conde Dr\u00e1cula<\/strong> (C. C. Humphreys)<\/li>\n<li><strong>Melocotones helados<\/strong> (Espido Freire)<\/li>\n<li><strong>Nada<\/strong> (Carmen Laforet)<\/li>\n<li><strong>La mujer de agua<\/strong> (Carmen Rigalt)<\/li>\n<li><strong>Nosotras que no somos como las dem\u00e1s<\/strong> (Luc\u00eda Etxebarr\u00eda)<\/li>\n<li><strong>La Eva fruta<\/strong> (Luc\u00eda Etxebarr\u00eda)<\/li>\n<li><strong>La letra Futura<\/strong> (Luc\u00eda Etxebarr\u00eda)<\/li>\n<li><strong>Beatriz y los cuerpos celestes<\/strong> (Luc\u00eda Etxebarr\u00eda)<\/li>\n<li><strong>Peque\u00f1as infamias<\/strong> (Carmen Posadas)<\/li>\n<li><strong>Eva Luna<\/strong> (Isabel Allende)<\/li>\n<li><strong>La destrucci\u00f3n del amor<\/strong> (Vicente Aleixandre)<\/li>\n<li><strong>El balneario<\/strong> (Carmen Mart\u00edn Gaite)<\/li>\n<li><strong>Aprender a pensar con libertad<\/strong> (Jos\u00e9 Antonio J\u00e1uregui)<\/li>\n<li><strong>Retrato en sepia<\/strong> (Isabel Allende)<\/li>\n<li><strong>Reinas malditas<\/strong> (Cristina Morat\u00f3)<\/li>\n<li><strong>Chocolate<\/strong> (Joanne Harris)<\/li>\n<li><strong>Locos de la historia<\/strong> (Alejandra Vallejo-N\u00e1gera)<\/li>\n<li><strong>El desv\u00e1n<\/strong> (Susana Prieto y Lea V\u00e9lez)<\/li>\n<li><strong>El diario de Bridget Jones<\/strong> (Helen Fielding)<\/li>\n<li><strong>La cultura, todo lo que hay que saber<\/strong> (Dietrich Schwanitz)<\/li>\n<li><strong>Los Pilares de la Tierra<\/strong> (Ken Follett)<\/li>\n<li><strong>Todos los nombres<\/strong> (Jos\u00e9 Saramago)<\/li>\n<li><strong>Ensayo sobre la ceguera<\/strong> (Jos\u00e9 Saramago)<\/li>\n<li><strong>Malena es un nombre de tango<\/strong> (Almudena Grandes)<\/li>\n<li><strong>Atlas de geograf\u00eda humana<\/strong> (Almudena Grandes)<\/li>\n<li><strong>La sombra del viento<\/strong> (Carlos Ruiz Zaf\u00f3n)<\/li>\n<li><strong>Rabia<\/strong> (Stephen King)<\/li>\n<li><strong>Legado en los huesos<\/strong> (Dolores Redondo)<\/li>\n<li><strong>El libro de los Baltimore<\/strong> (Jo\u00ebl Dicker)<\/li>\n<li><strong>La reina descalza<\/strong> (Idelfonso Falcones)<\/li>\n<li><strong>La isla bajo el mar<\/strong> (Isabel Allende)<\/li>\n<li><strong>La hermandad de la S\u00e1bana Santa<\/strong> (Julia Navarro)<\/li>\n<li><strong>Despu\u00e9s del amor<\/strong> (Sonsoles \u00d3nega)<\/li>\n<li><strong>La princesa de hielo<\/strong> (Camila L\u00e4ckberg)<\/li>\n<li><strong>El \u00faltimo Cat\u00f3n<\/strong> (Matilde Asensio)<\/li>\n<li><strong>La conspiraci\u00f3n<\/strong> (Dan Brown)<\/li>\n<li><strong>Ri\u00f1a de gatos, Madrid 1936<\/strong> (Eduardo Mendoza)<\/li>\n<li><strong>T\u00fa no matar\u00e1s<\/strong> (Julia Navarro)<\/li>\n<li><strong>La leyenda del ladr\u00f3n<\/strong> (Juan G\u00f3mez-Jurado)<\/li>\n<li><strong>El mundo<\/strong> (Juan Jos\u00e9 Mill\u00e1s)<\/li>\n<\/ol>\n<p>Para hacer la<strong> reserva del libro<\/strong> deber\u00e1s escribir un correo a<strong> cbp@residenciarucab.es,<\/strong> indicando el t\u00edtulo del libro, tu nombre y apellidos y el n\u00famero de habitaci\u00f3n. Dejaremos lo antes posible el libro en la puerta de tu habitaci\u00f3n.<\/p>\n<h4>NORMAS:<\/h4>\n<ul>\n<li>Vas a recibir el libro en buen estado, <strong>devu\u00e9lvelo igual.<\/strong><\/li>\n<li>Un vez lo hayas le\u00eddo, deber\u00e1s meterlo en una\u00a0<strong> bolsa<\/strong>.<\/li>\n<li>Llama a recepci\u00f3n y avisa de que ya has finalizado su lectura.<\/li>\n<li>Se te avisar\u00e1 del d\u00eda y la hora que se proceder\u00e1 a su recogida y en ese instante deber\u00e1s dejarlo en la puerta.<\/li>\n<li>S\u00f3lo podr\u00e1s hacer uso de un libro. Hasta que no devuelvas el primero no podr\u00e1s coger otro.<\/li>\n<li>La entrega de libros se har\u00e1 de<strong> lunes a viernes<\/strong> en horario de <strong>8.00 a 15.00 h<\/strong>.<\/li>\n<li>Una vez recibas el libro y cada vez que vayas a leerlo, te recomendamos que <strong>te laves las manos<\/strong> previamente.<\/li>\n<li>Una vez entregado el libro, pasar\u00e1 un periodo de <strong>cuarentena de 14 d\u00edas<\/strong>, para garantizar que la pr\u00f3xima persona que lo solicite lo reciba en condiciones de seguridad.<\/li>\n<\/ul>\n<p>Para cualquier duda o consulta llamar a <strong>Vanesa\u00a0 824 90 85 22<\/strong> o <strong>Cristina 824 90 85 23.\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1191 size-full\" src=\"http:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1.jpg\" alt=\"libros para el confinamiento covid-19\" width=\"1280\" height=\"720\" srcset=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1.jpg 1280w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1-300x169.jpg 300w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1-1024x576.jpg 1024w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1-768x432.jpg 768w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1-1140x641.jpg 1140w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/libros-confinamiento-coronavirus-1-552x311.jpg 552w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"post-excerpt\">\u00bfAburrimiento durante el aislamiento? queremos cambiarlo y hacerlo m\u00e1s ameno, os traemos &#8216;libros para el confinamiento&#8217;, ser\u00e1 de gran ayuda poner a disposici\u00f3n de los residentes confinados por el covid-19 el acceso a libros de tipo literario. En este post te explicamos c\u00f3mo tienes que hacerlo. Ahora muchas personas est\u00e1n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[9,294,295,296,130,7,36,35,297],"class_list":["post-1186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-badajoz","tag-confinamiento","tag-escritor","tag-ken-follett","tag-libros","tag-literatura","tag-residencia-universitaria","tag-rucab","tag-stephen-king"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Libros para el confinamiento en la RUCAB - BLOG RUCAB<\/title>\n<meta name=\"description\" content=\"Os traemos &#039;libros para el confinamiento&#039;, ponemos a disposici\u00f3n de los residentes confinados, el acceso a libros para sobrellevarlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libros para el confinamiento en la RUCAB - BLOG RUCAB\" \/>\n<meta property=\"og:description\" content=\"Os traemos &#039;libros para el confinamiento&#039;, ponemos a disposici\u00f3n de los residentes confinados, el acceso a libros para sobrellevarlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG RUCAB\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-05T14:07:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T08:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RUCAB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"RUCAB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/\"},\"author\":{\"name\":\"RUCAB\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#\\\/schema\\\/person\\\/f759c867eac865f0ce36c767f26f9294\"},\"headline\":\"Libros para el confinamiento en la RUCAB\",\"datePublished\":\"2020-11-05T14:07:34+00:00\",\"dateModified\":\"2020-11-06T08:27:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/\"},\"wordCount\":746,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg\",\"keywords\":[\"Badajoz\",\"confinamiento\",\"escritor\",\"Ken follett\",\"libros\",\"literatura\",\"Residencia Universitaria\",\"Rucab\",\"stephen king\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/\",\"name\":\"Libros para el confinamiento en la RUCAB - BLOG RUCAB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg\",\"datePublished\":\"2020-11-05T14:07:34+00:00\",\"dateModified\":\"2020-11-06T08:27:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#\\\/schema\\\/person\\\/f759c867eac865f0ce36c767f26f9294\"},\"description\":\"Os traemos 'libros para el confinamiento', ponemos a disposici\u00f3n de los residentes confinados, el acceso a libros para sobrellevarlo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg\",\"contentUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg\",\"width\":1280,\"height\":720,\"caption\":\"prestamos libros biblioteca rucab\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/libros-para-el-confinamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libros para el confinamiento en la RUCAB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/\",\"name\":\"BLOG RUCAB\",\"description\":\"\u00a1Todas las novedades de nuestra residencia universitaria!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#\\\/schema\\\/person\\\/f759c867eac865f0ce36c767f26f9294\",\"name\":\"RUCAB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/r-rosa.png\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/r-rosa.png\",\"contentUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/r-rosa.png\",\"caption\":\"RUCAB\"},\"description\":\"La RUCAB es un referente en Extremadura por la calidad de sus instalaciones y por su estilo de vida, basado en valores de convivencia, respeto y educaci\u00f3n. Una residencia junto al campus y con todas las necesidades cubiertas.\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/author\\\/rucab_blog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libros para el confinamiento en la RUCAB - BLOG RUCAB","description":"Os traemos 'libros para el confinamiento', ponemos a disposici\u00f3n de los residentes confinados, el acceso a libros para sobrellevarlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/","og_locale":"es_ES","og_type":"article","og_title":"Libros para el confinamiento en la RUCAB - BLOG RUCAB","og_description":"Os traemos 'libros para el confinamiento', ponemos a disposici\u00f3n de los residentes confinados, el acceso a libros para sobrellevarlo.","og_url":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/","og_site_name":"BLOG RUCAB","article_published_time":"2020-11-05T14:07:34+00:00","article_modified_time":"2020-11-06T08:27:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg","type":"image\/jpeg"}],"author":"RUCAB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"RUCAB","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#article","isPartOf":{"@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/"},"author":{"name":"RUCAB","@id":"https:\/\/residenciarucab.es\/blog\/#\/schema\/person\/f759c867eac865f0ce36c767f26f9294"},"headline":"Libros para el confinamiento en la RUCAB","datePublished":"2020-11-05T14:07:34+00:00","dateModified":"2020-11-06T08:27:09+00:00","mainEntityOfPage":{"@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/"},"wordCount":746,"commentCount":0,"image":{"@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg","keywords":["Badajoz","confinamiento","escritor","Ken follett","libros","literatura","Residencia Universitaria","Rucab","stephen king"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/","url":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/","name":"Libros para el confinamiento en la RUCAB - BLOG RUCAB","isPartOf":{"@id":"https:\/\/residenciarucab.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#primaryimage"},"image":{"@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg","datePublished":"2020-11-05T14:07:34+00:00","dateModified":"2020-11-06T08:27:09+00:00","author":{"@id":"https:\/\/residenciarucab.es\/blog\/#\/schema\/person\/f759c867eac865f0ce36c767f26f9294"},"description":"Os traemos 'libros para el confinamiento', ponemos a disposici\u00f3n de los residentes confinados, el acceso a libros para sobrellevarlo.","breadcrumb":{"@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#primaryimage","url":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg","contentUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2020\/11\/LIBROS-PARA-EL-CONFINAMIENTO-BLOG.jpg","width":1280,"height":720,"caption":"prestamos libros biblioteca rucab"},{"@type":"BreadcrumbList","@id":"https:\/\/residenciarucab.es\/blog\/libros-para-el-confinamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/residenciarucab.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Libros para el confinamiento en la RUCAB"}]},{"@type":"WebSite","@id":"https:\/\/residenciarucab.es\/blog\/#website","url":"https:\/\/residenciarucab.es\/blog\/","name":"BLOG RUCAB","description":"\u00a1Todas las novedades de nuestra residencia universitaria!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/residenciarucab.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/residenciarucab.es\/blog\/#\/schema\/person\/f759c867eac865f0ce36c767f26f9294","name":"RUCAB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2019\/07\/r-rosa.png","url":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2019\/07\/r-rosa.png","contentUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2019\/07\/r-rosa.png","caption":"RUCAB"},"description":"La RUCAB es un referente en Extremadura por la calidad de sus instalaciones y por su estilo de vida, basado en valores de convivencia, respeto y educaci\u00f3n. Una residencia junto al campus y con todas las necesidades cubiertas.","url":"https:\/\/residenciarucab.es\/blog\/author\/rucab_blog\/"}]}},"_links":{"self":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts\/1186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/comments?post=1186"}],"version-history":[{"count":12,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts\/1186\/revisions"}],"predecessor-version":[{"id":1193,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts\/1186\/revisions\/1193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/media\/1190"}],"wp:attachment":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/media?parent=1186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/categories?post=1186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/tags?post=1186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}