

{"id":2206,"date":"2023-09-04T10:01:44","date_gmt":"2023-09-04T08:01:44","guid":{"rendered":"https:\/\/residenciarucab.es\/blog\/?p=2206"},"modified":"2023-09-04T10:30:34","modified_gmt":"2023-09-04T08:30:34","slug":"organizar-una-erasmus","status":"publish","type":"post","link":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/","title":{"rendered":"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo?"},"content":{"rendered":"<h4>Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico, lugar donde los tacos y las salsas picantes nunca pueden faltar.<\/h4>\n<p>De primera mano les puedo contar que vivir un intercambio en un pa\u00eds tan lejos de casa implica mucho <strong>compromiso y responsabilidad<\/strong>, es una oportunidad \u00fanica y que debe disfrutarse y aprovecharse al m\u00e1ximo. Por tanto, cuando alguien planea emprender este proceso, se deben cubrir muchos puntos importantes con anticipaci\u00f3n. Aprovecho este espacio para platicarles, desde mi experiencia, algunos de estos puntos y mi vivencia con respecto a ellos.<\/p>\n<p>Lo primero y m\u00e1s importante: <strong>definir la universidad<\/strong> a la que te gustar\u00eda asistir, ya sea porque te ofrecen el plan de estudio m\u00e1s af\u00edn a tus intereses o porque se localiza en un lugar que te encantar\u00eda conocer. En mi caso, la <a href=\"https:\/\/www.unex.es\/\" target=\"_blank\" rel=\"noopener\">Universidad de Extremadura<\/a> me ofreci\u00f3 asignaturas afines a mi \u00e1rea de acentuaci\u00f3n, el \u00e1rea de salud. Los cambios en el <strong>sistema educativo y las formas de evaluar<\/strong> con respecto a mi pa\u00eds son diferentes, por lo que es muy importante tener apertura a esos cambios y aprovechar al m\u00e1ximo todas las experiencias y retos.<\/p>\n<p>Bueno, una vez aceptado en la universidad, es imprescindible que tengas opciones<strong> d\u00f3nde alojarte<\/strong>, pues representa uno de los mayores gastos. Como estudiantes buscamos un lugar que, obviamente, est\u00e9 en buenas condiciones, tenga cercan\u00eda con la universidad y lugares de inter\u00e9s, as\u00ed como buen contacto con la ciudad en general. En mi caso, tuve la suerte de encontrar la residencia <strong>RUCAB<\/strong>, donde siempre se han mostrado y, hasta la fecha, se muestran interesados en ayudarme en cualquier cosa que necesite. Sus instalaciones son muy completas, cuentan con todos los espacios necesarios para llevar a cabo nuestras actividades como estudiantes. Adem\u00e1s, las <strong>amistades que se forman dentro y fuera de la residencia son invaluables<\/strong>, pues he tenido la oportunidad de compartir con ellos mis experiencias y de enriquecerme con las suyas.<\/p>\n<p>Agradezco siempre toda la cercan\u00eda y ayuda que me han otorgado todas las personas que conforman la residencia.<\/p>\n<h4>Organ\u00edzate<\/h4>\n<p>Otro punto muy importante a considerar es la <strong>documentaci\u00f3n<\/strong> que se solicita para poder migrar a otro pa\u00eds (en especial cuando se encuentra fuera de la Uni\u00f3n Europea como en mi caso). Recomiendo realizar estos pasos con la mayor antelaci\u00f3n posible para evitar retrasos en el proceso.<\/p>\n<p>Por otro lado, siempre es bueno <strong>investigar lugares de inter\u00e9s<\/strong> que se encuentren alrededor del pa\u00eds donde realizamos el intercambio ya que, como estudiantes, contamos con m\u00faltiples beneficios que se deben aprovechar. He tenido la oportunidad de conocer distintos lugares dentro y fuera de Espa\u00f1a, como son Sevilla, C\u00f3rdoba, Madrid, Valencia, Lisboa, Par\u00eds, \u00c1msterdam, Berl\u00edn, entre otros.<\/p>\n<p>Aun cuando todos estos procesos puedan resultar algo tediosos y consumir mucho de nuestro tiempo, es a\u00fan m\u00e1s satisfactorio lograrlo y estar a la espera de todas las nuevas <strong>experiencias<\/strong> por vivir.<\/p>\n<p>Desde mi experiencia les recomiendo ampliamente a aquellos que tengan la intenci\u00f3n de vivir un intercambio o Erasmus que no se queden con las ganas de vivirlo, es una oportunidad \u00fanica en la vida como estudiantes que, desde mi experiencia, te ofrece mucho <strong>crecimiento tanto acad\u00e9mico como personal<\/strong> y, sobre todo, muchas amistades que se conservan para toda la vida. A\u00fan me quedan unos meses en Espa\u00f1a y me emociona mucho saber que nuevas experiencias tendr\u00e9 por delante.<\/p>\n<p>Tengan la seguridad de que M\u00e9xico los recibir\u00e1 siempre con mucha emoci\u00f3n, \u00a1mucho \u00e9xito!<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2206 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/2-10\/'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"Vania de M\u00e9xico y Sarah de Oporto\" srcset=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2-1024x576.jpg 1024w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2-300x169.jpg 300w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2-768x432.jpg 768w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2-1140x641.jpg 1140w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2-552x311.jpg 552w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/2.jpg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/4-11\/'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"Facultad de Ingenier\u00eda en Biotecnolog\u00eda\" srcset=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4-1024x576.jpg 1024w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4-300x169.jpg 300w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4-768x432.jpg 768w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4-1140x641.jpg 1140w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4-552x311.jpg 552w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/4.jpg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/5-8\/'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"Pr\u00e1cticas de Ingenier\u00eda en Biotecnolog\u00eda\" srcset=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5-1024x576.jpg 1024w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5-300x169.jpg 300w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5-768x432.jpg 768w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5-1140x641.jpg 1140w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5-552x311.jpg 552w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/5.jpg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/1-web-rucab-intercambio-mexico\/'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" src=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"Vania con compa\u00f1eros de la universidad.\" srcset=\"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico-1024x576.jpg 1024w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico-300x169.jpg 300w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico-768x432.jpg 768w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico-1140x641.jpg 1140w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico-552x311.jpg 552w, https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/1-web-rucab-intercambio-mexico.jpg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Puedes leer m\u00e1s contenido de los residentes\u00a0<a href=\"https:\/\/residenciarucab.es\/blog\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"post-excerpt\">Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico, lugar donde los tacos y las salsas picantes nunca pueden faltar. De primera mano les puedo contar que vivir un intercambio en un pa\u00eds tan lejos de casa implica mucho compromiso y responsabilidad,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[86,458,459,81],"class_list":["post-2206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-erasmus","tag-intercambio","tag-mexico","tag-universidad-de-extremadura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo? - BLOG RUCAB<\/title>\n<meta name=\"description\" content=\"\u00a1Hola! Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo? - BLOG RUCAB\" \/>\n<meta property=\"og:description\" content=\"\u00a1Hola! Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG RUCAB\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-04T08:01:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T08:30:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RUCAB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"RUCAB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/\"},\"author\":{\"name\":\"RUCAB\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#\\\/schema\\\/person\\\/f759c867eac865f0ce36c767f26f9294\"},\"headline\":\"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo?\",\"datePublished\":\"2023-09-04T08:01:44+00:00\",\"dateModified\":\"2023-09-04T08:30:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/\"},\"wordCount\":633,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3.jpg\",\"keywords\":[\"erasmus\",\"intercambio\",\"M\u00e9xico\",\"universidad de extremadura\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/\",\"name\":\"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo? - BLOG RUCAB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3.jpg\",\"datePublished\":\"2023-09-04T08:01:44+00:00\",\"dateModified\":\"2023-09-04T08:30:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#\\\/schema\\\/person\\\/f759c867eac865f0ce36c767f26f9294\"},\"description\":\"\u00a1Hola! Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Intercambio de Vania M\u00e9xico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/organizar-una-erasmus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/\",\"name\":\"BLOG RUCAB\",\"description\":\"\u00a1Todas las novedades de nuestra residencia universitaria!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/#\\\/schema\\\/person\\\/f759c867eac865f0ce36c767f26f9294\",\"name\":\"RUCAB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/r-rosa.png\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/r-rosa.png\",\"contentUrl\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/r-rosa.png\",\"caption\":\"RUCAB\"},\"description\":\"La RUCAB es un referente en Extremadura por la calidad de sus instalaciones y por su estilo de vida, basado en valores de convivencia, respeto y educaci\u00f3n. Una residencia junto al campus y con todas las necesidades cubiertas.\",\"url\":\"https:\\\/\\\/residenciarucab.es\\\/blog\\\/author\\\/rucab_blog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo? - BLOG RUCAB","description":"\u00a1Hola! Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/","og_locale":"es_ES","og_type":"article","og_title":"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo? - BLOG RUCAB","og_description":"\u00a1Hola! Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico.","og_url":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/","og_site_name":"BLOG RUCAB","article_published_time":"2023-09-04T08:01:44+00:00","article_modified_time":"2023-09-04T08:30:34+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/3.jpg","type":"image\/jpeg"}],"author":"RUCAB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"RUCAB","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#article","isPartOf":{"@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/"},"author":{"name":"RUCAB","@id":"https:\/\/residenciarucab.es\/blog\/#\/schema\/person\/f759c867eac865f0ce36c767f26f9294"},"headline":"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo?","datePublished":"2023-09-04T08:01:44+00:00","dateModified":"2023-09-04T08:30:34+00:00","mainEntityOfPage":{"@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/"},"wordCount":633,"commentCount":0,"image":{"@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#primaryimage"},"thumbnailUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/3.jpg","keywords":["erasmus","intercambio","M\u00e9xico","universidad de extremadura"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/","url":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/","name":"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo? - BLOG RUCAB","isPartOf":{"@id":"https:\/\/residenciarucab.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#primaryimage"},"image":{"@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#primaryimage"},"thumbnailUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/3.jpg","datePublished":"2023-09-04T08:01:44+00:00","dateModified":"2023-09-04T08:30:34+00:00","author":{"@id":"https:\/\/residenciarucab.es\/blog\/#\/schema\/person\/f759c867eac865f0ce36c767f26f9294"},"description":"\u00a1Hola! Mi nombre es Vania Garmendia, estudiante de intercambio en Ingenier\u00eda en Biotecnolog\u00eda y vengo de Obreg\u00f3n, M\u00e9xico.","breadcrumb":{"@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#primaryimage","url":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/3.jpg","contentUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2023\/09\/3.jpg","width":1280,"height":720,"caption":"Intercambio de Vania M\u00e9xico"},{"@type":"BreadcrumbList","@id":"https:\/\/residenciarucab.es\/blog\/organizar-una-erasmus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/residenciarucab.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Quiero irme de intercambio, \u00bfpor d\u00f3nde empiezo?"}]},{"@type":"WebSite","@id":"https:\/\/residenciarucab.es\/blog\/#website","url":"https:\/\/residenciarucab.es\/blog\/","name":"BLOG RUCAB","description":"\u00a1Todas las novedades de nuestra residencia universitaria!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/residenciarucab.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/residenciarucab.es\/blog\/#\/schema\/person\/f759c867eac865f0ce36c767f26f9294","name":"RUCAB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2019\/07\/r-rosa.png","url":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2019\/07\/r-rosa.png","contentUrl":"https:\/\/residenciarucab.es\/blog\/wp-content\/uploads\/2019\/07\/r-rosa.png","caption":"RUCAB"},"description":"La RUCAB es un referente en Extremadura por la calidad de sus instalaciones y por su estilo de vida, basado en valores de convivencia, respeto y educaci\u00f3n. Una residencia junto al campus y con todas las necesidades cubiertas.","url":"https:\/\/residenciarucab.es\/blog\/author\/rucab_blog\/"}]}},"_links":{"self":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/comments?post=2206"}],"version-history":[{"count":9,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts\/2206\/revisions"}],"predecessor-version":[{"id":2220,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/posts\/2206\/revisions\/2220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/media\/2213"}],"wp:attachment":[{"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/media?parent=2206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/categories?post=2206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/residenciarucab.es\/blog\/wp-json\/wp\/v2\/tags?post=2206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}